{"id":135114,"date":"2025-01-29T16:47:53","date_gmt":"2025-01-29T14:47:53","guid":{"rendered":"https:\/\/peimar.com\/2-0\/?page_id=135114"},"modified":"2025-10-10T09:46:00","modified_gmt":"2025-10-10T07:46:00","slug":"microinverter","status":"publish","type":"page","link":"https:\/\/peimar.com\/fr\/download\/microinverter\/","title":{"rendered":"Micro-onduleur"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-0\"><div class=\"row-background background-element\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"background-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"background-inner\" style=\"background-image: url(https:\/\/peimar.com\/wp-content\/uploads\/2025\/01\/95-scaled.jpg);background-repeat: no-repeat;background-position: center center;background-attachment: scroll;background-size: cover;\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-bg-overlay style-color-214632-bg\" style=\"opacity: 0.2;\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div><div class=\"row col-half-gutter exa-top-padding double-bottom-padding double-h-padding limit-width row-parent\" style=\"max-width:1500px; margin-left:auto; margin-right:auto;\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_center column_parent col-lg-12 no-internal-gutter\"><div class=\"uncol style-spec style-dark\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"empty-space empty-single desktop-hidden tablet-hidden\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h2 class=\"fontsize-155944 text-color-xsdn-color\" ><span>Micro-onduleur<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode_text_column text-small text-color-xsdn-color\" ><p>D\u00e9couvrez nos micro-onduleurs : efficacit\u00e9 et performance optimales pour chaque syst\u00e8me photovolta\u00efque.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-0\" data-row=\"script-row-unique-0\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-0\"));<\/script><\/div><\/div><\/div><section data-parent=\"true\" class=\"vc_section row-container\" id=\"section-unique-0\"><div class=\"row no-top-padding no-bottom-padding no-h-padding full-width row-parent\"><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-1\"><div class=\"row col-no-gutter triple-top-padding no-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_parent col-lg-1 mobile-hidden col-md-16 col-sm-16 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"icon-box icon-box-top  icon-media-image\" ><div class=\"icon-box-icon fa-container\" style=\"width:36px;margin-bottom: 0px;\" ><span class=\"text-default-color btn-disable-hover\"><img decoding=\"async\" class=\"\" src=\"https:\/\/peimar.com\/wp-content\/uploads\/2024\/03\/124.png\" width=\"96\" height=\"96\" alt=\"\"  \/><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left column_parent col-lg-11 col-md-75 col-sm-100 no-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-sezione\"><div class=\"heading-text el-text\" ><h3 class=\"h3 fontspace-111509 text-color-210407-color\" ><span>Fiche technique<\/span><\/h3><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-1\" data-row=\"script-row-unique-1\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-1\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-2\"><div class=\"row single-top-padding no-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 no-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-accordion wpb_accordion wpb_content_element  download-titolo-accordion plus-signed sign-size-rg default-typography w-border no-content-border tabs-trigger-box-resized\" data-collapsible=\"no\" data-target=\"row\" data-active-tab=\"0\" data-a-classes=\"single-block-padding no-h-padding\" >\n\t\t<div class=\"panel-group wpb_wrapper wpb_accordion_wrapper\" id=\"accordion_803840470\" data-no-toggle=\"\">\n\n<div class=\"panel panel-default wpb_accordion_section group  single-block-padding has-padding no-h-padding\"><div class=\"panel-heading wpb_accordion_header ui-accordion-header\"><p class=\"panel-title h5 font-weight-500 text-   icon-size-rg\"><a data-toggle=\"collapse\" data-parent=\"#accordion_803840470\" href=\"#schede-tecniche-micro-monofase\" data-tab-history=\"true\" data-tab-history-changer=\"push\" data-tab-history-update-url=\"true\" class=\"single-block-padding no-h-padding\"><span>PSI-X1P - Micro-onduleur monophas\u00e9<\/span><\/a><\/p><\/div><div data-id=\"schede-tecniche-micro-monofase\" class=\"panel-collapse collapse\"><div class=\"panel-body wpb_accordion_content ui-accordion-content half-internal-gutter no-block-padding\">\n\t\t\t\t\t\t<div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"divider-wrapper\"  >\n    <hr class=\"unseparator separator-no-padding\"  \/>\n<\/div>\n<div class=\"vc_row no-translation-class row-internal row-container\" data-no-translation=\"\"><div class=\"row unequal col-half-gutter row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_child col-lg-6 col-md-50 col-sm-66 no-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>PSI-X1P800-MIC<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left align_right_tablet column_child col-lg-6 col-md-50 col-sm-33 half-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-link\"><div class=\"heading-text el-text\" ><h2 class=\"h6 fontheight-524109 font-weight-300\" ><span><a href=\"https:\/\/peimar.com\/datasheet\/Peimar_IT_PSI-X1P800-MIC.pdf\" target=\"_blank\" rel=\"noopener\">IT<\/a>\u00a0 \u00a0 <a href=\"https:\/\/peimar.com\/datasheet\/Peimar_EN_PSI-X1P800-MIC.pdf\" target=\"_blank\" rel=\"noopener\">EN<\/a>\u00a0 \u00a0 <a href=\"https:\/\/peimar.com\/datasheet\/Peimar_FR_PSI-X1P800-MIC.pdf\" target=\"_blank\" rel=\"noopener\">FR<\/a>\u00a0 \u00a0 <a href=\"https:\/\/peimar.com\/datasheet\/Peimar_ES_PSI-X1P800-MIC.pdf\" target=\"_blank\" rel=\"noopener\">ESP<\/a>\u00a0 \u00a0 <a href=\"https:\/\/peimar.com\/datasheet\/Peimar_DE_PSI-X1P800-MIC.pdf\" target=\"_blank\" rel=\"noopener\">DE<\/a><\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"divider-wrapper\"  >\n    <hr class=\"unseparator separator-no-padding\"  \/>\n<\/div>\n<div class=\"vc_row no-translation-class row-internal row-container\" data-no-translation=\"\"><div class=\"row unequal col-half-gutter row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_child col-lg-6 col-md-50 col-sm-66 no-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>PSI-X1P1000-MIC<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left align_right_tablet column_child col-lg-6 col-md-50 col-sm-33 half-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-link\"><div class=\"heading-text el-text\" ><h2 class=\"h6 fontheight-524109 font-weight-300\" ><span><a href=\"https:\/\/peimar.com\/datasheet\/Peimar_IT_PSI-X1P1000-MIC.pdf\" target=\"_blank\" rel=\"noopener\">IT<\/a>\u00a0 \u00a0 <a href=\"https:\/\/peimar.com\/datasheet\/Peimar_EN_PSI-X1P1000-MIC.pdf\" target=\"_blank\" rel=\"noopener\">EN<\/a>\u00a0 \u00a0 <a href=\"https:\/\/peimar.com\/datasheet\/Peimar_FR_PSI-X1P1000-MIC.pdf\" target=\"_blank\" rel=\"noopener\">FR<\/a>\u00a0 \u00a0 <a href=\"https:\/\/peimar.com\/datasheet\/Peimar_ES_PSI-X1P1000-MIC.pdf\" target=\"_blank\" rel=\"noopener\">ESP<\/a>\u00a0 \u00a0 <a href=\"https:\/\/peimar.com\/datasheet\/Peimar_DE_PSI-X1P1000-MIC.pdf\" target=\"_blank\" rel=\"noopener\">DE<\/a><\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"empty-space empty-single\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<\/div><\/div><\/div><div class=\"panel panel-default wpb_accordion_section group  single-block-padding has-padding no-h-padding\"><div class=\"panel-heading wpb_accordion_header ui-accordion-header\"><p class=\"panel-title h5 font-weight-500 text-   icon-size-rg\"><a data-toggle=\"collapse\" data-parent=\"#accordion_803840470\" href=\"#schede-tecniche-micro-accessori\" data-tab-history=\"true\" data-tab-history-changer=\"push\" data-tab-history-update-url=\"true\" class=\"single-block-padding no-h-padding\"><span>Accessoires pour micro-onduleurs<\/span><\/a><\/p><\/div><div data-id=\"schede-tecniche-micro-accessori\" class=\"panel-collapse collapse\"><div class=\"panel-body wpb_accordion_content ui-accordion-content half-internal-gutter no-block-padding\">\n\t\t\t\t\t\t<div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"divider-wrapper\"  >\n    <hr class=\"unseparator separator-no-padding\"  \/>\n<\/div>\n<div class=\"vc_row row-internal row-container\"><div class=\"row unequal col-half-gutter row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_child col-lg-6 col-md-50 col-sm-66 no-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-scheda ; no-translation-class\" data-no-translation=\"\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>PSI-X1P-MIC<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"vc_custom_heading_wrap download-sottotitolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>ACCESSOIRES POUR LES SYST\u00c8MES DE MICRO-ONDULEURS SIMPLES ET MULTIPLES<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left align_right_tablet column_child col-lg-6 col-md-50 col-sm-33 half-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-link ; no-translation-class\" data-no-translation=\"\"><div class=\"heading-text el-text\" ><h2 class=\"h6 fontheight-524109 font-weight-300\" ><span><a href=\"https:\/\/peimar.com\/datasheet\/Peimar_IT_PSI-X1P-MIC_Accessori.pdf\" target=\"_blank\" rel=\"noopener\">IT<\/a>\u00a0 \u00a0 <a href=\"https:\/\/peimar.com\/datasheet\/Peimar_EN_PSI-X1P-MIC_Accessories.pdf\" target=\"_blank\" rel=\"noopener\">EN<\/a>\u00a0 \u00a0 <a href=\"https:\/\/peimar.com\/datasheet\/Peimar_FR_PSI-X1P-MIC_Accessories.pdf\" target=\"_blank\" rel=\"noopener\">FR<\/a><\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"divider-wrapper\"  >\n    <hr class=\"unseparator separator-no-padding\"  \/>\n<\/div>\n<div class=\"vc_row no-translation-class row-internal row-container\" data-no-translation=\"\"><div class=\"row unequal col-half-gutter row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_child col-lg-6 col-md-50 col-sm-66 no-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>PSI-XMIC-ECC<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left align_right_tablet column_child col-lg-6 col-md-50 col-sm-33 half-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-link\"><div class=\"heading-text el-text\" ><h2 class=\"h6 fontheight-524109 font-weight-300\" ><span><a href=\"https:\/\/peimar.com\/datasheet\/Peimar_EN_PSI-XMIC-ECC.pdf\" target=\"_blank\" rel=\"noopener\">EN<\/a>\u00a0 \u00a0 <a href=\"https:\/\/peimar.com\/datasheet\/Peimar_FR_PSI-XMIC-ECC.pdf\" target=\"_blank\" rel=\"noopener\">FR<\/a><\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"empty-space empty-single\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<\/div><\/div><\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-2\" data-row=\"script-row-unique-2\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-2\"));<\/script><\/div><\/div><\/div><script id=\"script-section-unique-0\" data-section=\"script-section-unique-0\" type=\"text\/javascript\">UNCODE.initSection(document.getElementById(\"section-unique-0\"));<\/script><\/div><\/section><section data-parent=\"true\" class=\"vc_section row-container\" id=\"section-unique-1\"><div class=\"row no-top-padding no-bottom-padding no-h-padding full-width row-parent\"><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-3\"><div class=\"row col-no-gutter triple-top-padding no-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_parent col-lg-1 mobile-hidden col-md-16 col-sm-16 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"icon-box icon-box-top  icon-media-image\" ><div class=\"icon-box-icon fa-container\" style=\"width:36px;margin-bottom: 0px;\" ><span class=\"text-default-color btn-disable-hover\"><img decoding=\"async\" class=\"\" src=\"https:\/\/peimar.com\/wp-content\/uploads\/2024\/03\/125.png\" width=\"96\" height=\"96\" alt=\"\"  \/><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left column_parent col-lg-10 col-md-66 col-sm-100 no-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-sezione\"><div class=\"heading-text el-text\" ><h2 class=\"h2 fontspace-111509 text-color-210407-color\" ><span>Manuale d&#8217;installazione<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-3\" data-row=\"script-row-unique-3\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-3\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-4\"><div class=\"row single-top-padding no-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 no-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-accordion wpb_accordion wpb_content_element  download-titolo-accordion plus-signed sign-size-rg default-typography w-border no-content-border tabs-trigger-box-resized\" data-collapsible=\"no\" data-target=\"row\" data-active-tab=\"0\" data-a-classes=\"single-block-padding no-h-padding\" >\n\t\t<div class=\"panel-group wpb_wrapper wpb_accordion_wrapper\" id=\"accordion_196366175\" data-no-toggle=\"\">\n\n<div class=\"panel panel-default wpb_accordion_section group  single-block-padding has-padding no-h-padding\"><div class=\"panel-heading wpb_accordion_header ui-accordion-header\"><p class=\"panel-title h5 font-weight-500 text-   icon-size-rg\"><a data-toggle=\"collapse\" data-parent=\"#accordion_196366175\" href=\"#manuale-micro-monofase\" data-tab-history=\"true\" data-tab-history-changer=\"push\" data-tab-history-update-url=\"true\" class=\"single-block-padding no-h-padding\"><span>PSI-X1P - Micro-onduleur monophas\u00e9<\/span><\/a><\/p><\/div><div data-id=\"manuale-micro-monofase\" class=\"panel-collapse collapse\"><div class=\"panel-body wpb_accordion_content ui-accordion-content half-internal-gutter no-block-padding\">\n\t\t\t\t\t\t<div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"divider-wrapper\"  >\n    <hr class=\"unseparator separator-no-padding\"  \/>\n<\/div>\n<div class=\"vc_row no-translation-class row-internal row-container\" data-no-translation=\"\"><div class=\"row unequal col-half-gutter row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_child col-lg-6 col-md-50 col-sm-66 no-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>PSI-X1P-MIC<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"vc_custom_heading_wrap download-sottotitolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>PSI-X1P800-MIC | PSI-X1P1000-MIC<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left align_right_tablet column_child col-lg-6 col-md-50 col-sm-33 half-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-link\"><div class=\"heading-text el-text\" ><h2 class=\"h6 fontheight-524109 font-weight-300\" ><span><a href=\"http:\/\/peimar.com\/documents\/Peimar_IT_user-manual_PSI-X1P800-1000-MIC.pdf\" target=\"_blank\" rel=\"noopener\">IT<\/a> \u00a0 \u00a0<a href=\"http:\/\/peimar.com\/documents\/Peimar_EN_user-manual_PSI-X1P800-1000-MIC.pdf\" target=\"_blank\" rel=\"noopener\">EN<\/a>\u00a0 \u00a0 <a href=\"http:\/\/peimar.com\/documents\/Peimar_FR_user-manual_PSI-X1P800-1000-MIC.pdf\" target=\"_blank\" rel=\"noopener\">FR<\/a><\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"empty-space empty-single\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<\/div><\/div><\/div><div class=\"panel panel-default wpb_accordion_section group  single-block-padding has-padding no-h-padding\"><div class=\"panel-heading wpb_accordion_header ui-accordion-header\"><p class=\"panel-title h5 font-weight-500 text-   icon-size-rg\"><a data-toggle=\"collapse\" data-parent=\"#accordion_196366175\" href=\"#manuale-micro-accessori\" data-tab-history=\"true\" data-tab-history-changer=\"push\" data-tab-history-update-url=\"true\" class=\"single-block-padding no-h-padding\"><span>Accessoires pour micro-onduleurs<\/span><\/a><\/p><\/div><div data-id=\"manuale-micro-accessori\" class=\"panel-collapse collapse\"><div class=\"panel-body wpb_accordion_content ui-accordion-content half-internal-gutter no-block-padding\">\n\t\t\t\t\t\t<div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"divider-wrapper\"  >\n    <hr class=\"unseparator separator-no-padding\"  \/>\n<\/div>\n<div class=\"vc_row no-translation-class row-internal row-container\" data-no-translation=\"\"><div class=\"row unequal col-half-gutter row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_child col-lg-6 col-md-50 col-sm-66 no-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>PSI-XMIC-ECC<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left align_right_tablet column_child col-lg-6 col-md-50 col-sm-33 half-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-link\"><div class=\"heading-text el-text\" ><h2 class=\"h6 fontheight-524109 font-weight-300\" ><span><a href=\"http:\/\/peimar.com\/documents\/Peimar_IT_user-manual_PSI-XMIC-ECC.pdf\" target=\"_blank\" rel=\"noopener\">IT<\/a> \u00a0 \u00a0<a href=\"https:\/\/peimar.com\/documents\/Peimar_EN_user-manual_PSI-XMIC-ECC.pdf\" target=\"_blank\" rel=\"noopener\">EN<\/a>\u00a0 \u00a0 <a href=\"https:\/\/peimar.com\/documents\/Peimar_FR_user-manual_PSI-XMIC-ECC.pdf\" target=\"_blank\" rel=\"noopener\">FR<\/a><\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"empty-space empty-single\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<\/div><\/div><\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-4\" data-row=\"script-row-unique-4\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-4\"));<\/script><\/div><\/div><\/div><script id=\"script-section-unique-1\" data-section=\"script-section-unique-1\" type=\"text\/javascript\">UNCODE.initSection(document.getElementById(\"section-unique-1\"));<\/script><\/div><\/section><section data-parent=\"true\" class=\"vc_section row-container\" id=\"section-unique-2\"><div class=\"row no-top-padding no-bottom-padding no-h-padding full-width row-parent\"><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-5\"><div class=\"row col-no-gutter triple-top-padding no-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_parent col-lg-1 mobile-hidden col-md-16 col-sm-16 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"icon-box icon-box-top  icon-media-image\" ><div class=\"icon-box-icon fa-container\" style=\"width:36px;margin-bottom: 0px;\" ><span class=\"text-default-color btn-disable-hover\"><img decoding=\"async\" class=\"\" src=\"https:\/\/peimar.com\/wp-content\/uploads\/2024\/03\/127.png\" width=\"96\" height=\"96\" alt=\"\"  \/><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left column_parent col-lg-10 col-md-66 col-sm-100 no-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-sezione\"><div class=\"heading-text el-text\" ><h2 class=\"h2 fontspace-111509 text-color-210407-color\" ><span>Certifications<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-5\" data-row=\"script-row-unique-5\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-5\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-6\"><div class=\"row single-top-padding no-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 no-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-accordion wpb_accordion wpb_content_element  download-titolo-accordion plus-signed sign-size-rg default-typography w-border no-content-border tabs-trigger-box-resized\" data-collapsible=\"no\" data-target=\"row\" data-active-tab=\"0\" data-a-classes=\"single-block-padding no-h-padding\" >\n\t\t<div class=\"panel-group wpb_wrapper wpb_accordion_wrapper\" id=\"accordion_51552514\" data-no-toggle=\"\">\n\n<div class=\"panel panel-default wpb_accordion_section group  single-block-padding has-padding no-h-padding\"><div class=\"panel-heading wpb_accordion_header ui-accordion-header\"><p class=\"panel-title h5 font-weight-500 text-   icon-size-rg\"><a data-toggle=\"collapse\" data-parent=\"#accordion_51552514\" href=\"#monofase-cei0-21\" data-tab-history=\"true\" data-tab-history-changer=\"push\" data-tab-history-update-url=\"true\" class=\"single-block-padding no-h-padding\"><span>CEI 0-21<\/span><\/a><\/p><\/div><div data-id=\"monofase-cei0-21\" class=\"panel-collapse collapse\"><div class=\"panel-body wpb_accordion_content ui-accordion-content half-internal-gutter no-block-padding\">\n\t\t\t\t\t\t<div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"divider-wrapper\"  >\n    <hr class=\"unseparator separator-no-padding\"  \/>\n<\/div>\n<div class=\"vc_row row-internal row-container\"><div class=\"row unequal col-half-gutter row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_child col-lg-6 no-translation-class col-md-50 col-sm-100 no-internal-gutter\" data-no-translation=\"\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>PSI-X1P-MIC<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"vc_custom_heading_wrap download-sottotitolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>PSI-X1P800-MIC | PSI-X1P1000-MIC<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"empty-space empty-half desktop-hidden tablet-hidden\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left align_left_tablet column_child col-lg-6 col-md-50 col-sm-100 col-sm-clear no-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-link-piccolo\"><div class=\"heading-text el-text\" ><h2 class=\"h6 fontheight-524109 font-weight-300\" ><span>D\u00e9claration de conformit\u00e9*<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"vc_custom_heading_wrap download-titolo-link ; no-translation-class\" data-no-translation=\"\"><div class=\"heading-text el-text\" ><h2 class=\"h6 fontheight-524109 font-weight-300\" ><span><a href=\"http:\/\/peimar.com\/certificate\/Dichiarazione%20di%20conformita%20CEI-021-2024-01_PSI-X1P-0.75-1.2K_MIC_r0%20-%20Signed.pdf\" target=\"_blank\" rel=\"noopener\">Link<\/a><\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"divider-wrapper\"  >\n    <hr class=\"unseparator separator-no-padding\"  \/>\n<\/div>\n<div class=\"vc_row row-internal row-container\"><div class=\"row row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_child col-lg-12 no-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>CERTIFICATS V COMPTE \u00c9NERGIE - (INSPECTION D'USINE, ETC.)<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"vc_custom_heading_wrap download-sottotitolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5 fontspace-111509\" ><span>CERTIFICATS V COMPTABILISATION ENERGETIQUE - Inspection d'usine IEC61215 \/ 61730 etc.<br \/><\/span><span>Contactez le support technique (assistenza@peimar.com) pour demander des certificats pour des produits sp\u00e9cifiques achet\u00e9s ou \u00e0 acheter.<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"vc_custom_heading_wrap download-sottotitolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5 fontspace-111509\" ><span><b>* Document d'identit\u00e9 du d\u00e9clarant omis car la d\u00e9claration de conformit\u00e9 est d\u00e9livr\u00e9e sous la forme d'une d\u00e9claration tenant lieu d'affidavit conform\u00e9ment \u00e0 l'article 21 du d\u00e9cret pr\u00e9sidentiel 445\/2000.<\/b><\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"empty-space empty-single\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-6\" data-row=\"script-row-unique-6\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-6\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-7\"><div class=\"row col-no-gutter triple-top-padding no-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_parent col-lg-1 mobile-hidden col-md-16 col-sm-16 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"icon-box icon-box-top  icon-media-image\" ><div class=\"icon-box-icon fa-container\" style=\"width:36px;margin-bottom: 0px;\" ><span class=\"text-default-color btn-disable-hover\"><img decoding=\"async\" class=\"\" src=\"https:\/\/peimar.com\/wp-content\/uploads\/2024\/04\/110.png\" width=\"96\" height=\"96\" alt=\"\"  \/><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left column_parent col-lg-10 col-md-66 col-sm-100 no-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-sezione\"><div class=\"heading-text el-text\" ><h2 class=\"h2 fontspace-111509 text-color-210407-color\" ><span>Outils de surveillance et de configuration<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-7\" data-row=\"script-row-unique-7\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-7\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-8\"><div class=\"row single-top-padding no-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 no-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-accordion wpb_accordion wpb_content_element  download-titolo-accordion plus-signed sign-size-rg default-typography w-border no-content-border tabs-trigger-box-resized\" data-collapsible=\"no\" data-target=\"row\" data-active-tab=\"0\" data-a-classes=\"single-block-padding no-h-padding\" >\n\t\t<div class=\"panel-group wpb_wrapper wpb_accordion_wrapper\" id=\"accordion_1575698766\" data-no-toggle=\"\">\n\n<div class=\"panel panel-default wpb_accordion_section group  single-block-padding has-padding no-h-padding\"><div class=\"panel-heading wpb_accordion_header ui-accordion-header\"><p class=\"panel-title h5 font-weight-500 text-   icon-size-rg\"><a data-toggle=\"collapse\" data-parent=\"#accordion_1575698766\" href=\"#strumenti\" data-tab-history=\"true\" data-tab-history-changer=\"push\" data-tab-history-update-url=\"true\" class=\"single-block-padding no-h-padding\"><span>Outils<\/span><\/a><\/p><\/div><div data-id=\"strumenti\" class=\"panel-collapse collapse\"><div class=\"panel-body wpb_accordion_content ui-accordion-content half-internal-gutter no-block-padding\">\n\t\t\t\t\t\t<div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"divider-wrapper\"  >\n    <hr class=\"unseparator separator-no-padding\"  \/>\n<\/div>\n<div class=\"vc_row row-internal row-container\"><div class=\"row unequal col-half-gutter row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_child col-lg-6 col-md-50 col-sm-66 no-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>GUIDE DE CONFIGURATION<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"vc_custom_heading_wrap download-sottotitolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>SYST\u00c8ME DE SURVEILLANCE DE L'ONDULEUR PSI-X<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left align_right_tablet align_right_mobile column_child col-lg-6 col-md-50 col-sm-33 half-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-link ; no-translation-class\" data-no-translation=\"\"><div class=\"heading-text el-text\" ><h2 class=\"h6 fontheight-524109 font-weight-300\" ><span><a href=\"https:\/\/peimar.com\/documents\/Peimar_Configurazione%20del%20sistema%20di%20monitoraggio%20inverter%20PSI-X.pdf\" target=\"_blank\" rel=\"noopener\">IT<\/a>&nbsp; &nbsp; <a href=\"http:\/\/peimar.com\/documents\/Peimar_Configuration%20du%20syst%C3%A8me%20de%20surveillance%20des%20onduleurs%20PSI-X.pdf\" target=\"_blank\" rel=\"noopener\">FR<\/a><\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"divider-wrapper\"  >\n    <hr class=\"unseparator separator-no-padding\"  \/>\n<\/div>\n<div class=\"vc_row row-internal row-container\"><div class=\"row unequal col-half-gutter row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_child col-lg-6 col-md-50 col-sm-66 no-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>MANUALE D&#8217;USO PORTALE PEIMAR X PORTAL<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"vc_custom_heading_wrap download-sottotitolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>SYST\u00c8ME DE SURVEILLANCE DES ONDULEURS DE LA S\u00c9RIE X<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left align_right_tablet align_right_mobile column_child col-lg-6 col-md-50 col-sm-33 half-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-link ; no-translation-class\" data-no-translation=\"\"><div class=\"heading-text el-text\" ><h2 class=\"h6 fontheight-524109 font-weight-300\" ><span><a href=\"http:\/\/peimar.com\/documents\/Peimar_IT_PeimarXportal_user_manual.pdf\" target=\"_blank\" rel=\"noopener\">IT<\/a>&nbsp; &nbsp; <a href=\"http:\/\/peimar.com\/documents\/Peimar_EN_PeimarXportal_user_manual.pdf\" target=\"_blank\" rel=\"noopener\">EN<\/a>&nbsp; &nbsp; <a href=\"http:\/\/peimar.com\/documents\/Peimar_FR_PeimarXportal_user_manual.pdf\" target=\"_blank\" rel=\"noopener\">FR<\/a><\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"divider-wrapper\"  >\n    <hr class=\"unseparator separator-no-padding\"  \/>\n<\/div>\n<div class=\"vc_row row-internal row-container\"><div class=\"row unequal col-half-gutter row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_child col-lg-6 col-md-50 col-sm-66 no-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>PORTAL PEIMAR<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"vc_custom_heading_wrap download-sottotitolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>ONDULEURS DE LA S\u00c9RIE PSI-X<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left align_right_tablet align_right_mobile column_child col-lg-6 col-md-50 col-sm-33 half-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-link ; no-translation-class\" data-no-translation=\"\"><div class=\"heading-text el-text\" ><h2 class=\"h6 fontheight-524109 font-weight-300\" ><span><a href=\"https:\/\/www.peimar-psix-portal.com\/#\/login\" target=\"_blank\" rel=\"noopener\">Link<\/a><\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"divider-wrapper\"  >\n    <hr class=\"unseparator separator-no-padding\"  \/>\n<\/div>\n<div class=\"vc_row row-internal row-container\"><div class=\"row unequal col-half-gutter row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_child col-lg-6 col-md-50 col-sm-66 no-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>PEIMAR DESIGNER<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left align_right_tablet align_right_mobile column_child col-lg-6 col-md-50 col-sm-33 half-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-link ; no-translation-class\" data-no-translation=\"\"><div class=\"heading-text el-text\" ><h2 class=\"h6 fontheight-524109 font-weight-300\" ><span><a href=\"https:\/\/designer.peimar.com\/login\" target=\"_blank\" rel=\"noopener\">Link<\/a><\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"empty-space empty-single\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"empty-space empty-single\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<\/div><\/div><\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-8\" data-row=\"script-row-unique-8\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-8\"));<\/script><\/div><\/div><\/div><script id=\"script-section-unique-2\" data-section=\"script-section-unique-2\" type=\"text\/javascript\">UNCODE.initSection(document.getElementById(\"section-unique-2\"));<\/script><\/div><\/section><section data-parent=\"true\" class=\"vc_section row-container\" id=\"section-unique-3\"><div class=\"row no-top-padding no-bottom-padding no-h-padding full-width row-parent\"><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-9\"><div class=\"row col-no-gutter triple-top-padding no-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_parent col-lg-1 mobile-hidden col-md-16 col-sm-16 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"icon-box icon-box-top  icon-media-image\" ><div class=\"icon-box-icon fa-container\" style=\"width:36px;margin-bottom: 0px;\" ><span class=\"text-default-color btn-disable-hover\"><img decoding=\"async\" class=\"\" src=\"https:\/\/peimar.com\/wp-content\/uploads\/2024\/03\/126.png\" width=\"96\" height=\"96\" alt=\"\"  \/><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left column_parent col-lg-10 col-md-66 col-sm-100 no-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-sezione\"><div class=\"heading-text el-text\" ><h2 class=\"h2 fontspace-111509 text-color-210407-color\" ><span>Garantie<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-9\" data-row=\"script-row-unique-9\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-9\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-10\"><div class=\"row single-top-padding no-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 no-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-accordion wpb_accordion wpb_content_element  download-titolo-accordion plus-signed sign-size-rg default-typography w-border no-content-border tabs-trigger-box-resized\" data-collapsible=\"no\" data-target=\"row\" data-active-tab=\"0\" data-a-classes=\"single-block-padding no-h-padding\" >\n\t\t<div class=\"panel-group wpb_wrapper wpb_accordion_wrapper\" id=\"accordion_2012803971\" data-no-toggle=\"\">\n\n<div class=\"panel panel-default wpb_accordion_section group  single-block-padding has-padding no-h-padding\"><div class=\"panel-heading wpb_accordion_header ui-accordion-header\"><p class=\"panel-title h4 font-weight-500 text-   icon-size-rg\"><a data-toggle=\"collapse\" data-parent=\"#accordion_2012803971\" href=\"#garanzia\" data-tab-history=\"true\" data-tab-history-changer=\"push\" data-tab-history-update-url=\"true\" class=\"single-block-padding no-h-padding\"><span>Garantie<\/span><\/a><\/p><\/div><div data-id=\"garanzia\" class=\"panel-collapse collapse\"><div class=\"panel-body wpb_accordion_content ui-accordion-content half-internal-gutter no-block-padding\">\n\t\t\t\t\t\t<div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"divider-wrapper\"  >\n    <hr class=\"unseparator separator-no-padding\"  \/>\n<\/div>\n<div class=\"vc_row row-internal row-container\"><div class=\"row unequal col-half-gutter row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_child col-lg-6 col-md-50 col-sm-50 half-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-scheda\"><div class=\"heading-text el-text\" ><h2 class=\"h5\" ><span>GARANTIE DES ONDULEURS DE LA SERIE PSI-X<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left align_right_tablet align_right_mobile column_child col-lg-6 col-md-50 col-sm-50 half-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap download-titolo-link ; no-translation-class\" data-no-translation=\"\"><div class=\"heading-text el-text\" ><h2 class=\"h6 fontheight-524109 font-weight-300\" ><span><a href=\"https:\/\/peimar.com\/documents\/Peimar_IT_GARANZIA-INVERTER-PSI-X.pdf\" target=\"_blank\" rel=\"noopener\">IT<\/a>\u00a0 \u00a0 <a href=\"http:\/\/peimar.com\/documents\/Peimar_EN_PSI-X-SERIES-INVERTER-WARRANTY.pdf\" target=\"_blank\" rel=\"noopener\">EN<\/a>\u00a0 \u00a0 <a href=\"http:\/\/peimar.com\/documents\/Peimar_FR_GARANTIE-INVERTER-PSI-X.pdf\" target=\"_blank\" rel=\"noopener\">FR<\/a><\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"empty-space empty-single\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<\/div><\/div><\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-10\" data-row=\"script-row-unique-10\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-10\"));<\/script><\/div><\/div><\/div><script id=\"script-section-unique-3\" data-section=\"script-section-unique-3\" type=\"text\/javascript\">UNCODE.initSection(document.getElementById(\"section-unique-3\"));<\/script><\/div><\/section><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-12\"><div class=\"row quad-top-padding triple-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_center column_parent col-lg-12 no-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h6 class=\"font-weight-400 text-color-210407-color\" ><span>Pour plus de certifications et de documents, veuillez contacter notre service assistance technique : <em><a href=\"mailto:assistenza@peimar.com\" target=\"_blank\" rel=\"noopener\">assistenza@peimar.com<\/a><\/em><\/span><\/h6><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-12\" data-row=\"script-row-unique-12\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-12\"));<\/script><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Made in Italy &#038; Half cell<\/p>","protected":false},"author":12,"featured_media":0,"parent":130684,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-135114","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/peimar.com\/fr\/wp-json\/wp\/v2\/pages\/135114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/peimar.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/peimar.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/peimar.com\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/peimar.com\/fr\/wp-json\/wp\/v2\/comments?post=135114"}],"version-history":[{"count":0,"href":"https:\/\/peimar.com\/fr\/wp-json\/wp\/v2\/pages\/135114\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/peimar.com\/fr\/wp-json\/wp\/v2\/pages\/130684"}],"wp:attachment":[{"href":"https:\/\/peimar.com\/fr\/wp-json\/wp\/v2\/media?parent=135114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}